{"id":6012,"date":"2023-08-26T18:30:29","date_gmt":"2023-08-26T16:30:29","guid":{"rendered":"https:\/\/criolloquetzal.ch\/?post_type=product&#038;p=6012"},"modified":"2026-05-13T03:14:26","modified_gmt":"2026-05-13T01:14:26","slug":"nahua-dunkle-schokolade-75-kakaonibs-costa-rica","status":"publish","type":"product","link":"https:\/\/criolloquetzal.ch\/de\/produit\/nahua-dunkle-schokolade-75-kakaonibs-costa-rica\/","title":{"rendered":"Nahua - Dunkle Schokolade 75% mit Kakaonibs - COSTA RICA"},"content":{"rendered":"<p>\u200bKenner werden die 70%ige dunkle Schokolade von Nahua mit ihren grossen Kakaost\u00fcckchen (Nibs) lieben.<\/p>\n<p>Die Tafeln von Nahua, obwohl sie sehr einfach gehalten sind,\u00a0bieten eine reichhaltige und befriedigend cremige Textur und bewahren gleichzeitig das tiefe, intensive Bouquet der Aromen des feinen Kakaos aus dem sie hergestellt sind.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u200bKenner werden die 70%ige dunkle Schokolade von Nahua mit ihren grossen Kakaost\u00fcckchen (Nibs) lieben. Die Tafeln von Nahua, obwohl sie sehr einfach gehalten sind,\u00a0bieten eine reichhaltige und befriedigend cremige Textur und bewahren gleichzeitig das tiefe, intensive Bouquet der Aromen des feinen Kakaos aus dem sie hergestellt sind.<\/p>\n","protected":false},"featured_media":5959,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[780,97],"product_tag":[],"class_list":{"0":"post-6012","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-costa-rica-de","7":"product_cat-zentralamerika","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"outofstock","bundle_stock_quantity":0,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":{"ingredients":"\u200b\u200bKakaomasse (69% Costa Rica), Zucker, Kakaonibs, Kakaobutter","energie":620,"graisse":56,"graisse_saturee":28,"glucides":44,"sucre":24,"fibre":"16","proteines":16,"sel":0},"_links":{"self":[{"href":"https:\/\/criolloquetzal.ch\/de\/wp-json\/wp\/v2\/product\/6012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/criolloquetzal.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/criolloquetzal.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/criolloquetzal.ch\/de\/wp-json\/wp\/v2\/media\/5959"}],"wp:attachment":[{"href":"https:\/\/criolloquetzal.ch\/de\/wp-json\/wp\/v2\/media?parent=6012"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/criolloquetzal.ch\/de\/wp-json\/wp\/v2\/product_brand?post=6012"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/criolloquetzal.ch\/de\/wp-json\/wp\/v2\/product_cat?post=6012"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/criolloquetzal.ch\/de\/wp-json\/wp\/v2\/product_tag?post=6012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}