{"id":9017,"date":"2025-08-02T10:13:43","date_gmt":"2025-08-02T08:13:43","guid":{"rendered":"https:\/\/criolloquetzal.ch\/produit\/definite-cioccolato-fondente-55-con-mandorle-caramellate-e-spezie-repubblica-dominicana\/"},"modified":"2026-05-13T04:44:20","modified_gmt":"2026-05-13T02:44:20","slug":"definite-cioccolato-fondente-55-mandorle-spezie-repubblica-dominicana","status":"publish","type":"product","link":"https:\/\/criolloquetzal.ch\/it\/produit\/definite-cioccolato-fondente-55-mandorle-spezie-repubblica-dominicana\/","title":{"rendered":"Definite - Cioccolato fondente 55% con mandorle caramellate e spezie - REPUBBLICA DOMINICANA"},"content":{"rendered":"<p>Questo cioccolato Definite vegano con il 55% di cacao \u00e8 deliziosamente cremoso. \u00c8 prodotto con anacardi e mandorle caramellate, aromatizzato inoltre con sottili note di spezie esotiche (noce moscata, cardamomo, chiodi di garofano, cannella, zenzero).<\/p>\n<p>Assaggia tutti i Caraibi in una tavoletta di cioccolato!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questo cioccolato Definite vegano con il 55% di cacao \u00e8 deliziosamente cremoso. \u00c8 prodotto con anacardi e mandorle caramellate, aromatizzato inoltre con sottili note di spezie esotiche (noce moscata, cardamomo, chiodi di garofano, cannella, zenzero). Assaggia tutti i Caraibi in una tavoletta di cioccolato!<\/p>\n","protected":false},"featured_media":8790,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[775,160],"product_tag":[],"class_list":{"0":"post-9017","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-repubblica-dominicana","7":"product_cat-caraibi","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"bundled_by":["9320"],"bundle_stock_status":"instock","bundle_stock_quantity":16,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":{"ingredients":"Fave di cacao (51% Repubblica Dominicana), zucchero di canna, burro di cacao, polvere di <strong data-verified=\"redactor\" data-redactor-tag=\"strong\">anacardi<\/strong>, <strong data-verified=\"redactor\" data-redactor-tag=\"strong\">mandorle<\/strong>, spezie","energie":560,"graisse":36,"graisse_saturee":20,"glucides":56,"sucre":36,"fibre":"8","proteines":8,"sel":0.002},"_links":{"self":[{"href":"https:\/\/criolloquetzal.ch\/it\/wp-json\/wp\/v2\/product\/9017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/criolloquetzal.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/criolloquetzal.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/criolloquetzal.ch\/it\/wp-json\/wp\/v2\/media\/8790"}],"wp:attachment":[{"href":"https:\/\/criolloquetzal.ch\/it\/wp-json\/wp\/v2\/media?parent=9017"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/criolloquetzal.ch\/it\/wp-json\/wp\/v2\/product_brand?post=9017"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/criolloquetzal.ch\/it\/wp-json\/wp\/v2\/product_cat?post=9017"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/criolloquetzal.ch\/it\/wp-json\/wp\/v2\/product_tag?post=9017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}